{"id":2836,"date":"2016-04-04T07:03:55","date_gmt":"2016-04-04T05:03:55","guid":{"rendered":"http:\/\/www.weiterbildungsmarkt.net\/magazin\/?p=2836"},"modified":"2017-01-22T09:40:44","modified_gmt":"2017-01-22T07:40:44","slug":"werden-sie-experte-eigener-sache-mehr-vitalitaet-fuer-sie","status":"publish","type":"post","link":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/werden-sie-experte-eigener-sache-mehr-vitalitaet-fuer-sie\/","title":{"rendered":"Werden Sie Experte in eigener Sache: Mehr Vitalit\u00e4t f\u00fcr Sie"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Gesund sein m\u00f6chten wohl alle, sich daf\u00fcr qu\u00e4len sicher niemand. In welchem Kontext auch immer medizinische Vorsorgema\u00dfnahmen angeboten werden, die Begeisterung der Menschen h\u00e4lt sich in Grenzen. Zu stark ist die Aura von Verzicht, Schwei\u00df und Tr\u00e4nen \u2013 das macht weder Spa\u00df noch gesund. Was also tun, wenn die eigenen Krankenst\u00e4nde oder jene in Familie und Betrieb ein bedenkliches Ausma\u00df annehmen? Weiterbildung kann da weiterhelfen \u2013 und Sie m\u00fcssen weder ein Medizin-Studium noch einen Pflege-Kurs absolvieren. Schummeln\u201c Sie die Gesundheit \u00fcber das \u201eVitalitaetsRad\u201c bei der Hintert\u00fcr hinein \u2013 auch an Ihrem eigenen inneren Schweinehund vorbei!<\/strong><\/p>\n<p style=\"text-align: justify;\">Vielleicht geht es Ihnen ja wie mir? Nach einigen Wartungen und Ersatzteilen hatte ich die Nase voll von den st\u00e4ndigen Werkstattbesuchen. Den K\u00f6rper und meine Verantwortung daf\u00fcr einfach abzugeben brachte mich dem Gesund-Sein nicht n\u00e4her. Nat\u00fcrlich braucht man in manchen F\u00e4llen einen Meister seines Fachs, aber wo genau ordiniert die Universalgelehrte, die \u00fcber einen umfassenden \u00dcberblick UND \u00fcber detaillierte Kenntnisse meiner individuellen Bed\u00fcrfnisse verf\u00fcgt? Ich machte mich also auf die Suche nach etwas Grundlegenderem \u2013 und fand die <strong>Vitalit\u00e4t<\/strong>. Ich verstehe darunter die <strong>ganz pers\u00f6nliche Lebenskraft<\/strong>, die alles schafft. Jeder von uns kommt damit schon auf die Welt, sozusagen als Geburtsrecht. Allerdings auch als Geburtspflicht, denn sie will gehegt und erhalten werden. Das hat jedoch nichts mit Ver- oder Geboten zu tun, vielmehr geht es darum, sich selbst zu sp\u00fcren und das zu tun, was einem guttut.<\/p>\n<p style=\"text-align: justify;\"><strong>Die Vitalit\u00e4t eines Menschen ist grundlegender und weitreichender als seine Gesundheit, weil sie k\u00f6rperliche, mentale, emotionale und soziale Faktoren umfasst<\/strong>. Man kann gesund sein und trotzdem ersch\u00f6pft. Und man kann krank sein und trotzdem voller Energie. Und selbst, wenn alles in bester Ordnung ist, l\u00e4sst sich das Wohlbefinden noch steigern.<\/p>\n<h2 style=\"text-align: justify;\">Noch gesund oder schon vital?<\/h2>\n<p style=\"text-align: justify;\">Unter diesem Motto hat die \u201eEglseer &amp; Zellermayer-Akademie f\u00fcr lebendige Unternehmen\u201c einen <strong>kostenlosen und wissenschaftlich<\/strong> zertifizierten <strong>Vitalit\u00e4tstest<\/strong> entwickelt. Seit kurzem steht das VitalitaetsRad\u00ae online zur Verf\u00fcgung. Der Test bietet mit rund hundert Fragen zu acht Lebensbereichen die M\u00f6glichkeit, den pers\u00f6nlichen Vitalit\u00e4tsIndex zu ermitteln \u2013 und in weiterer Folge zu verbessern. Das Ausf\u00fcllen des Fragebogens kostet <strong>keinen Euro<\/strong> und nimmt gerade mal ein <strong>halbe Stunde<\/strong> Zeit in Anspruch. Ein Gewinn f\u00fcr alle, die auf Dauer mehr vom Leben wollen: <strong>Mehr Energie, mehr Freude, mehr Qualit\u00e4t<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Die acht Lebensbereiche bzw. Vitalit\u00e4tsfaktoren:<\/h2>\n<ol>\n<li>Umfassende Achtsamkeit<\/li>\n<li>Optimistische Lebenseinstellung<\/li>\n<li>Resilientes Arbeiten<\/li>\n<li>K\u00f6rper-Bewusstsein<\/li>\n<li>Ern\u00e4hrungs- und Umwelt-Bewusstsein<\/li>\n<li>Liebevolle Selbstf\u00fcrsorge<\/li>\n<li>Erf\u00fcllende Sexualit\u00e4t<\/li>\n<li>Soziales Eingebunden-Sein<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Die Auswertung liefert ein <strong>Gesamtergebnis<\/strong> \u2013 in einem Spektrum von \u201eToll \u2013 wie machen Sie das?\u201c bis \u201eIhre Batterien sind v\u00f6llig leer\u201c \u2013 sowie die beiden Faktoren mit den jeweils besten und schlechtesten Ergebnissen. Aufgrund der individuellen Antworten ergeben sich Anhaltspunkte, wo die <strong>pers\u00f6nlichen Vitalit\u00e4ts-Lecks<\/strong> sind.<\/p>\n<h3 style=\"text-align: justify;\">Wenn Sie es sich nicht gut gehen lassen \u2013 wer tut es dann?<\/h3>\n<p style=\"text-align: justify;\">Der Test ist eine Momentaufnahme \u2013 und l\u00e4sst sich nat\u00fcrlich jederzeit wiederholen, um zu sehen, ob und wie sehr sich etwas getan hat. Es geht nicht darum, mit anderen in Wettstreit zu treten \u2013 wer ist die\/der Vitalste im ganzen Land \u2013, das Ausloten der eigenen M\u00f6glichkeiten ist das Ziel. Es gibt Bereiche, da kann einem kein Arzt helfen. Und es gibt kein Rezept \u2013 \u00e1 la man nehme eine Prise Konzentrationsf\u00e4higkeit, drei positive S\u00e4tze pro Tag, etwas Belastbarkeit, und so weiter \u2013 das f\u00fcr alle Menschen G\u00fcltigkeit h\u00e4tte. Die Elemente sind immer die gleichen, aber die richtige \u201eDosierung\u201c ist h\u00f6chst individuell. Umso mehr Spa\u00df macht es, sich selbst und seine Bed\u00fcrfnisse besser kennen zu lernen, allerhand auszuprobieren und langsam aber sicher sein pers\u00f6nliches Lebensfreude-Programm zu entwickeln. Das hat nichts mit \u201epauken\u201c zu tun, und doch lernt man eine Menge. Das sind oft nur Kleinigkeiten, die nicht viel Zeit und M\u00fche kosten und sich problemlos in den Alltag einbauen lassen. Genau die richtige Menge Schlaf, bewusstes Atmen, freudvolle Bewegung usw. \u2013 das klingt banal, aber seien Sie ehrlich zu sich selbst: Wissen Sie genau, was und wieviel Ihnen guttut? Und halten Sie sich daran?<\/p>\n<p style=\"text-align: justify;\">Diese Kleinigkeiten des Alltags sind so selbstverst\u00e4ndlich f\u00fcr uns, dass wir leider kaum noch einen Gedanken an sie verschwenden. Aber ihre Summe entscheidet \u00fcber unsere Lebensfreude. Es muss ja auch nicht alles auf einmal sein \u2013 setzen Sie Ihre Priorit\u00e4ten, erstellen Sie einen \u201eLehr\u201c- und Zeitplan. Gestalten und genie\u00dfen Sie Ihr Leben nach Ihren Vorstellungen \u2013 mit bestem Wissen und Gewissen, denn: Sowohl Ihre Familie als auch Ihr Unternehmen profitieren umso mehr, je besser es Ihnen geht.<\/p>\n<h3 style=\"text-align: justify;\">Fordern und f\u00f6rdern \u00fcberraschend anders<\/h3>\n<p style=\"text-align: justify;\">Am besten vermitteln sich Inhalte, indem sie vorgelebt werden. Das gilt f\u00fcr die vitalit\u00e4tsbewusste Lebensf\u00fchrung genauso wie in der Kindererziehung. Als verantwortungsbewusste(r) Familienmensch und\/oder F\u00fchrungskraft werden Sie durch mehr Vitalit\u00e4t wie von selbst zum Motivator: Das innere Leuchten wirkt ansteckend. Und das VitalitaetsRad l\u00e4sst sich wunderbar auch f\u00fcr gr\u00f6\u00dfere Personengruppen drehen. Leistung hat mindestens so viel mit Wohlbefinden zu tun wie mit Bereitschaft. Eine h\u00f6here Lebensqualit\u00e4t wirkt sich auf alle Lebensbereiche aus.<\/p>\n<p style=\"text-align: justify;\">Finden wir zur\u00fcck zur Eigenverantwortung, fragen wir uns, was uns fehlt und was wir brauchen, nehmen und geben wir uns Zeit, wieder heil zu werden. Wenn wir uns um unsere Vitalit\u00e4t k\u00fcmmern, stellt sich Gesundheit automatisch ein.<\/p>\n<h3 style=\"text-align: justify;\">2 sehr wichtige Fragen<strong><br \/>\n<\/strong><\/h3>\n<p style=\"text-align: justify;\">Abschlie\u00dfend zwei wichtige Fragen deren Beantwortung Sie schon mal auf die richtige F\u00e4hrte f\u00fchrt:<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>Wozu, <\/strong>auf welches Ziel hin, f\u00fcr wen, f\u00fcr welche Lebensaufgabe ergibt es Sinn, <strong>in meine Gesunderhaltung zu investieren?<\/strong><\/li>\n<li><strong>Was st\u00e4rkt mich besonders, so dass ich mich rundum wohl, gesund und vital f\u00fchle?<\/strong><\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\">\u00dcber den Autor:<\/h3>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-2837\" src=\"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-content\/uploads\/2016\/03\/Zellermayer-120x120.jpg\" alt=\"Zellermayer\" width=\"120\" height=\"120\" srcset=\"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-content\/uploads\/2016\/03\/Zellermayer-120x120.jpg 120w, https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-content\/uploads\/2016\/03\/Zellermayer-210x210.jpg 210w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/>Mag. Peter Zellermayer<\/strong> ist Unternehmens- sowie Lebens- und Sozialberater, Coach und Trainer. Gesch\u00e4ftsf\u00fchrer der EZ-Akademie<br \/>\nwww.vitalitaetsrad.at<\/p>\n<p style=\"text-align: justify;\">Hinweis: Neben dem Gratis-Angebot bietet die EZ-Akademie dar\u00fcber hinaus auch ein <strong>professionelles<\/strong> \u2013 und kostenpflichtiges \u2013 <strong>Vitalit\u00e4tsCoaching via Skype<\/strong> an. Das ist kein standardisiertes 08\/15-Programm, sondern eine auf die jeweiligen Bed\u00fcrfnisse eingehende Betreuung auf der Basis einer differenzierten Auswertung des Tests. Aus der Gehirnforschung wei\u00df man, dass Haltungs- und Verhaltens\u00e4nderungen einige Zeit der verst\u00e4rkten Achtsamkeit brauchen, bis sie sozusagen in Fleisch und Blut \u00fcbergegangen sind. Diese Phase \u2013 neun Wochen \u2013 wird durch das Coaching begleitet.<\/p>\n<p style=\"text-align: justify;\">Weitere Informationen \u00fcber die <a href=\"https:\/\/www.weiterbildungsmarkt.net\/institut-niederoesterreich-ez-akademie-1022\"><strong>EZ-Akademie<\/strong> <\/a><\/p>\n<p style=\"text-align: justify;\">\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fwerden-sie-experte-eigener-sache-mehr-vitalitaet-fuer-sie%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fwerden-sie-experte-eigener-sache-mehr-vitalitaet-fuer-sie%2F&text=Werden%20Sie%20Experte%20in%20eigener%20Sache%3A%20Mehr%20Vitalit%C3%A4t%20f%C3%BCr%20Sie\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fwerden-sie-experte-eigener-sache-mehr-vitalitaet-fuer-sie%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#126567; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fwerden-sie-experte-eigener-sache-mehr-vitalitaet-fuer-sie%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fwerden-sie-experte-eigener-sache-mehr-vitalitaet-fuer-sie%2F%20Werden%20Sie%20Experte%20in%20eigener%20Sache%3A%20Mehr%20Vitalit%C3%A4t%20f%C3%BCr%20Sie\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fwerden-sie-experte-eigener-sache-mehr-vitalitaet-fuer-sie%2F&media=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fwp-content%2Fuploads%2F2024%2F11%2Fcolored-pencils-2024-09-23-04-02-30-utc-scaled.jpg&description=Werden%20Sie%20Experte%20in%20eigener%20Sache%3A%20Mehr%20Vitalit%C3%A4t%20f%C3%BCr%20Sie\" title=\"Bei Pinterest pinnen\" aria-label=\"Bei Pinterest pinnen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#cb2027; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Gesund sein m\u00f6chten wohl alle, sich daf\u00fcr qu\u00e4len sicher niemand. In welchem Kontext auch immer medizinische Vorsorgema\u00dfnahmen angeboten werden, die Begeisterung der Menschen h\u00e4lt sich in Grenzen. Zu stark ist die Aura von Verzicht, Schwei\u00df und Tr\u00e4nen \u2013 das macht weder Spa\u00df noch gesund. Was also tun, wenn die eigenen Krankenst\u00e4nde oder jene in Familie [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9749,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5,44],"tags":[],"class_list":["post-2836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coaching","category-stressmanagement"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/posts\/2836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/comments?post=2836"}],"version-history":[{"count":4,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/posts\/2836\/revisions"}],"predecessor-version":[{"id":3883,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/posts\/2836\/revisions\/3883"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/media\/9749"}],"wp:attachment":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/media?parent=2836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/categories?post=2836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/tags?post=2836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}