{"id":3482,"date":"2017-02-21T08:04:56","date_gmt":"2017-02-21T06:04:56","guid":{"rendered":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/?p=3482"},"modified":"2017-01-18T18:22:26","modified_gmt":"2017-01-18T16:22:26","slug":"quo-vadis-personalentwicklung","status":"publish","type":"post","link":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/quo-vadis-personalentwicklung\/","title":{"rendered":"Quo vadis Personalentwicklung?"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Diese Frage stellt sich heute so vehement wie noch nie. Denn die meisten Unternehmen wissen heute noch nicht, wie viele Mitarbeiter und welche Kompetenzen sie in einigen Jahren brauchen. Deshalb ist eine strategische, also langfristig orientierte Personalentwicklung kaum noch m\u00f6glich.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201eWir betreiben eine strategische Personalentwicklung\u201c, \u201eUnsere Personalentwicklung orientiert sich an den strategischen Zielen des Unternehmens.\u201c Solche S\u00e4tze waren \u00fcber viele Jahre hinweg sozusagen die Kernaussagen der Personalentwickler in (Gro\u00df-)Unternehmen, wenn man mit ihnen \u00fcber ihre Arbeit und die ihrer Bereiche sprach. Und in ihnen dokumentierte sich zugleich ihr Selbstverst\u00e4ndnis \u2013 n\u00e4mlich strategische Partner der Unternehmensf\u00fchrung beim Erreichen der Unternehmensziele zu sein.<\/p>\n<p style=\"text-align: justify;\">Seit einigen Jahren vernimmt man solche Aussagen seltener. Und die oft auf viele Jahre, teils sogar Jahrzehnte angelegten F\u00fchrungs- und Managemententwicklungsprogramme, die die firmeninternen Personalentwickler so gerne und voller Stolz pr\u00e4sentierten \u2013 als Belege f\u00fcr ihre strategische Arbeitsweise? Sie wurden inzwischen in den meisten Unternehmen auf Eis gelegt \u2013 stillverschweigend und bei weitem nicht mit so viel Tamtam, wie ihr Start verk\u00fcndet wurde.<\/p>\n<p style=\"text-align: justify;\">Entsprechendes gilt f\u00fcr die Weiterbildung in den Unternehmen. Sie ist heute viel weniger an einer langfristigen Kompetenzentwicklung orientiert als noch vor einem Jahrzehnt oder gar zur Jahrtausendwende. Sie fokussiert sich heute weitgehend darauf, akute Kompetenzdefizite zu beheben, die sich zum Beispiel aus<\/p>\n<ul style=\"text-align: justify;\">\n<li>dem Einf\u00fchren neuer Technologien,<\/li>\n<li>dem Ver\u00e4ndern von Abl\u00e4ufen und Prozessen in der Organisation oder<\/li>\n<li>Marktver\u00e4nderungen ergeben.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>VUCA-Welt macht langfristige Planung obsolet<\/strong><\/p>\n<p style=\"text-align: justify;\">Die zentrale Ursache hierf\u00fcr ist: In der sogenannten VUCA-Welt (<a href=\"https:\/\/en.wiktionary.org\/wiki\/volatility\" target=\"_blank\" rel=\"noopener\">volatility<\/a>, <a href=\"https:\/\/en.wikipedia.org\/wiki\/Uncertainty\" target=\"_blank\" rel=\"noopener\">uncertainty<\/a>, <a href=\"https:\/\/en.wikipedia.org\/wiki\/Complexity\" target=\"_blank\" rel=\"noopener\">complexity<\/a>, <a href=\"https:\/\/en.wikipedia.org\/wiki\/Ambiguity\" target=\"_blank\" rel=\"noopener\">ambiguity<\/a>) von heute k\u00f6nnen Unternehmen nur noch bedingt einsch\u00e4tzen,<\/p>\n<ul style=\"text-align: justify;\">\n<li>wie sich ihr Markt in den n\u00e4chsten f\u00fcnf oder gar zehn Jahren entwickelt,<\/li>\n<li>welche Probleml\u00f6sungen dann aufgrund des technischen Fortschritts m\u00f6glich sind und<\/li>\n<li>welche Auswirkungen sich hieraus f\u00fcr ihr Gesch\u00e4ftsmodell ergeben.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Entsprechend kurzfristig sind ihre Strategien. Sie stehen sozusagen permanent auf dem Pr\u00fcfstand. Deshalb k\u00f6nnen sich in der VUCA-Welt auch viele personalpolitische und -strategische Entscheidungen, die heute sinnvoll erscheinen, in zwei, drei Jahren als falsch erweisen.<\/p>\n<p style=\"text-align: justify;\">Das bringt viele Unternehmen in folgendes Dilemma: Einerseits m\u00fcssen sie eine vorausschauende Personalpolitik betreiben, um sicher zu stellen, dass sie auch in einigen Jahren noch die ben\u00f6tigten Mitarbeiter mit den erforderlichen Kompetenzen haben \u2013 auch weil absehbar ist, dass in den westlichen Industrienationen gute Fach- und F\u00fchrungskr\u00e4fte k\u00fcnftig noch rarer werden; andererseits k\u00f6nnen sie heute oft noch nicht sagen,<\/p>\n<ul style=\"text-align: justify;\">\n<li>wie viele Mitarbeiter sie in drei, f\u00fcnf oder gar zehn Jahren brauchen und<\/li>\n<li>welche Kompetenzen ihre Organisation dann ben\u00f6tigt und ihre Mitarbeiter folglich brauchen.<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Funktion der Personalentwickler wandelt sich<\/h2>\n<p style=\"text-align: justify;\">Wie die Unternehmen dieses Dilemma (mittelfristig) l\u00f6sen beziehungsweise managen, das ist heute noch nicht vorhersagbar. Klar ist jedoch: Die Personalentwicklung, ja die Personalarbeit insgesamt in den Unternehmen wird sich in den n\u00e4chsten Jahren dramatisch ver\u00e4ndern. Eine ihrer Hauptfunktionen wird es k\u00fcnftig sein, relativ kurzfristig daf\u00fcr zu sorgen, dass ihrem Unternehmen die ben\u00f6tigten Mitarbeiter mit den erforderlichen Kompetenzen zur Verf\u00fcgung stehen, so dass dieses schnell zum Beispiel auf Marktver\u00e4nderungen reagieren kann.<\/p>\n<p style=\"text-align: justify;\">Ein erstes Indiz hierf\u00fcr ist die Ausweitung der Leiharbeit. W\u00e4hrend sie sich bis vor wenigen Jahren weitgehend auf die Produktionsbereiche und die produktionsnahen Bereiche beschr\u00e4nkte, ist es heute in den Unternehmen bereits gang und g\u00e4be, dass zum Beispiel auch in den Forschungs- und Entwicklungsabteilungen \u201eLeiharbeiter\u201c sitzen. Und sogar Bereichsleiter- und Projektleiter-Posten werden zunehmend mit \u201eLeiharbeitern\u201c besetzt.<\/p>\n<p style=\"text-align: justify;\">Diese \u201eLeiharbeiter\u201c oder Mitarbeiter auf Zeit werden zwar nicht Leiharbeiter, sondern meist \u201eInterim-Manager\u201c genannt; sie sind jedoch ein Beleg daf\u00fcr, dass den Unternehmen eigene Mitarbeiter mit den erforderlichen Kompetenzen fehlen. Diese Entwicklungstendenz wird sich verst\u00e4rken. Wenig gewagt ist die These: K\u00fcnftig werden die Unternehmen noch viel h\u00e4ufiger als heute ben\u00f6tigte Kompetenzen auf Zeit einkaufen, statt diese firmenintern aufzubauen und zu entwickeln<\/p>\n<h2 style=\"text-align: justify;\">Operative Ebene wird st\u00e4rker in die Pflicht genommen<\/h2>\n<p style=\"text-align: justify;\">Ein weiteres Indiz f\u00fcr einen Paradigmenwechsel in der Personalentwicklung ist, dass immer mehr Unternehmen propagieren: Die Personalentwicklungs-Kompetenz muss sich verst\u00e4rkt auf die operative Ebene verlagern. Das hei\u00dft: Ihre Mitarbeiter m\u00fcssen sich zu Selbstentwicklern entwickeln, die selbst daf\u00fcr sorgen, dass sie auch k\u00fcnftig \u00fcber die ben\u00f6tigte Kompetenz verf\u00fcgen. Und ihre F\u00fchrungskr\u00e4fte sollen sie hierbei\u00a0 unterst\u00fctzen.<\/p>\n<p style=\"text-align: justify;\">Diskutiert wurde hier\u00fcber unter dem Stichwort \u201eEmployability\u201c in Personalerkreisen bereits seit vielen Jahren. Dahinter stand die Erkenntnis: Der Ver\u00e4nderungsbedarf in den Unternehmen ist heute so gro\u00df, dass er zentral kaum noch erfasst werden kann. Zudem ist er in den einzelnen Bereichen und bei den einzelnen Mittarbeitern so verschieden, dass er mit zentral, also zum Beispiel von der Personalabteilung geplanten Ma\u00dfnahmen nicht mehr befriedigt werden kann \u2013 schon gar nicht in der erforderlichen kurzen Zeit. Was lange Zeit jedoch eher eine akademische Diskussion in Personalentwicklerkreisen war, ist nun in der betrieblichen Realit\u00e4t angekommen. Nahezu \u00fcbereinstimmend betonen heute fast alle gr\u00f6\u00dferen Unternehmen: Unsere Mitarbeiter sind auch selbst f\u00fcr die Entwicklung ihrer Kompetenz verantwortlich \u2013 unterst\u00fctzt von ihren F\u00fchrungskr\u00e4ften.<\/p>\n<h2 style=\"text-align: justify;\">Personalentwickler werden firmeninterne Dienstleister<\/h2>\n<p style=\"text-align: justify;\">Doch welche Funktion haben k\u00fcnftig dann noch die firmeninternen Personalentwickler?\u00a0 Eine zentrale Aufgabe von ihnen wird es sein, den Mitarbeitern auf der operativen Ebene (und ihren F\u00fchrungskr\u00e4ften) die Tools zur Verf\u00fcgung zu stellen, die diese zum Entwickeln ihrer Kompetenz brauchen. Hierbei wird es sich im Zuge der Digitalisierung der Unternehmen, auch diese These ist nicht gewagt, verst\u00e4rkt um Online-Tools handeln, wie sie bereits beim Blendend Learning zum Einsatz kommen.<\/p>\n<p style=\"text-align: justify;\">Eine weitere Kernaufgabe der Personalentwickler wird es sein, f\u00fcr das erforderliche Allignment bei der Kompetenzentwicklung in der Organisation zu sorgen, damit zum Beispiel die F\u00fchrungskr\u00e4fte und die Projektmanager im Unternehmen bei ihrer Arbeit weitgehend das F\u00fchrungs- beziehungsweise Projektmanagement-Verst\u00e4ndnis haben und nicht in unterschiedliche Richtungen ziehen.<\/p>\n<p style=\"text-align: justify;\">Diese Kernaufgaben professionell wahrzunehmen, setzt auch ein Umdenken bei den Personalentwicklern in den Unternehmen voraus. Inwieweit ihnen dies gelingt, wird eine der spannenden Fragen 2017 sein. Sie wird auch \u00fcber das k\u00fcnftige Standing der Personalentwicklung in den Unternehmen mitentscheiden.<\/p>\n<h3 style=\"text-align: justify;\">\u00dcber den Autor:<\/h3>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-2555\" src=\"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-content\/uploads\/2015\/11\/Mullerschon-Albrecht-Dr-360KB-120x120.jpg\" alt=\"Mullerschon, Albrecht\" width=\"120\" height=\"120\" srcset=\"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-content\/uploads\/2015\/11\/Mullerschon-Albrecht-Dr-360KB-120x120.jpg 120w, https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-content\/uploads\/2015\/11\/Mullerschon-Albrecht-Dr-360KB-210x210.jpg 210w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/>Dr. Albrecht M\u00fcllersch\u00f6n<\/strong> ist Inhaber der M\u00fcllersch\u00f6n Managementberatung, Starzeln (Baden-W\u00fcrttemberg), die Unternehmen und ihre Mitarbeiter beim Bew\u00e4ltigen von Changevorhaben unterst\u00fctzt. Der Wirtschaftspsychologe und Lehrcoach ist Autor mehrerer Personal-Fachb\u00fccher.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fquo-vadis-personalentwicklung%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fquo-vadis-personalentwicklung%2F&text=Quo%20vadis%20Personalentwicklung%3F\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fquo-vadis-personalentwicklung%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#126567; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fquo-vadis-personalentwicklung%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fquo-vadis-personalentwicklung%2F%20Quo%20vadis%20Personalentwicklung%3F\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fquo-vadis-personalentwicklung%2F&media=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fwp-content%2Fuploads%2F2024%2F11%2Fcolored-pencils-2024-09-23-04-02-30-utc-scaled.jpg&description=Quo%20vadis%20Personalentwicklung%3F\" title=\"Bei Pinterest pinnen\" aria-label=\"Bei Pinterest pinnen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#cb2027; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Diese Frage stellt sich heute so vehement wie noch nie. Denn die meisten Unternehmen wissen heute noch nicht, wie viele Mitarbeiter und welche Kompetenzen sie in einigen Jahren brauchen. Deshalb ist eine strategische, also langfristig orientierte Personalentwicklung kaum noch m\u00f6glich. \u201eWir betreiben eine strategische Personalentwicklung\u201c, \u201eUnsere Personalentwicklung orientiert sich an den strategischen Zielen des Unternehmens.\u201c [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9749,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7,61,50,1],"tags":[178,132,171],"class_list":["post-3482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-personalentwicklung","category-change-management","category-human-resource-management","category-weiterbildung","tag-change-management","tag-personalentwicklung","tag-personalmanagement"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/posts\/3482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/comments?post=3482"}],"version-history":[{"count":4,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/posts\/3482\/revisions"}],"predecessor-version":[{"id":3487,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/posts\/3482\/revisions\/3487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/media\/9749"}],"wp:attachment":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/media?parent=3482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/categories?post=3482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/tags?post=3482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}