{"id":4753,"date":"2017-08-20T14:07:56","date_gmt":"2017-08-20T12:07:56","guid":{"rendered":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/?p=4753"},"modified":"2018-06-18T05:18:22","modified_gmt":"2018-06-18T03:18:22","slug":"nuetzliche-tipps-um-muede-augen-im-buero-zu-entspannen","status":"publish","type":"post","link":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/nuetzliche-tipps-um-muede-augen-im-buero-zu-entspannen\/","title":{"rendered":"N\u00fctzliche Tipps, um m\u00fcde Augen im B\u00fcro zu entspannen"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Wer viel am Bildschirm arbeitet, kennt die Probleme, die damit einhergehen: Kopfschmerzen, brennende und trockene Augen, Schlafst\u00f6rungen durch das Blaulicht und sogar nachlassende Sehkraft sind nur einige Auswirkungen, die st\u00e4ndige Arbeit am PC und am Handy mit sich ziehen. Umso wichtiger ist es, den Augen mit ein paar Entspannungs\u00fcbungen f\u00fcr zwischendurch Erholung zu g\u00f6nnen. Beherzigen Sie ein paar n\u00fctzliche Tipps, die Ihre Augen Ihnen danken werden.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4755\" src=\"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-content\/uploads\/2017\/08\/iclinic-Infografik_Nie-wieder-muede-Augen.png\" alt=\"iclinic-Infografik_Nie wieder muede Augen\" width=\"1251\" height=\"4418\" srcset=\"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-content\/uploads\/2017\/08\/iclinic-Infografik_Nie-wieder-muede-Augen.png 1251w, https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-content\/uploads\/2017\/08\/iclinic-Infografik_Nie-wieder-muede-Augen-85x300.png 85w, https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-content\/uploads\/2017\/08\/iclinic-Infografik_Nie-wieder-muede-Augen-768x2712.png 768w, https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-content\/uploads\/2017\/08\/iclinic-Infografik_Nie-wieder-muede-Augen-290x1024.png 290w, https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-content\/uploads\/2017\/08\/iclinic-Infografik_Nie-wieder-muede-Augen-696x2458.png 696w, https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-content\/uploads\/2017\/08\/iclinic-Infografik_Nie-wieder-muede-Augen-1068x3772.png 1068w, https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-content\/uploads\/2017\/08\/iclinic-Infografik_Nie-wieder-muede-Augen-119x420.png 119w\" sizes=\"auto, (max-width: 1251px) 100vw, 1251px\" \/><\/p>\n<h2 style=\"text-align: justify;\">#1: Schaffen Sie g\u00fcnstige Arbeitsbedingungen<\/h2>\n<p style=\"text-align: justify;\">Zun\u00e4chst gilt es, die bestm\u00f6glichen Umweltbedingungen f\u00fcr Ihre Augen zu schaffen. Dazu geh\u00f6ren ein paar kleine Ma\u00dfnahmen, die es Ihren Augen angenehmer machen k\u00f6nnen. Beispielsweise sollten Sie den <strong>Bildschirm so positionieren, dass Sie nicht durch die einfallende Sonne darin geblendet werden<\/strong> oder sich das Licht darin unangenehm spiegelt. Ist dies aus bautechnischen Gr\u00fcnden nicht m\u00f6glich, sollten Sie zumindest einen <strong>Blendschutz<\/strong> am PC anbringen oder sich um entsprechende <strong>Rollos oder Vorh\u00e4nge<\/strong> f\u00fcr die Fenster bem\u00fchen, mit denen Sie die Helligkeit im Raum an Ihr Lichtbed\u00fcrfnis anpassen k\u00f6nnen. W\u00e4hlen Sie auch eine f\u00fcr Sie <strong>angenehme Bildschirmhelligkeit<\/strong> und legen Sie Kontraste nach Ihrem Wunsch fest.<\/p>\n<h2 style=\"text-align: justify;\">#2: Profitieren Sie von der Kraft der Natur<\/h2>\n<p style=\"text-align: justify;\">Mit nat\u00fcrlichen Mitteln k\u00f6nnen Sie Ihren Augen <strong>schnelle Linderung vom anstrengenden Alltag<\/strong> verschaffen. Folgende Tipps k\u00f6nnen Sie davon konkret beherzigen:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Wenn sich die Augen ganz trocken anf\u00fchlen oder jucken, <strong>sp\u00fclen Sie sie mit kaltem Wasser aus. <\/strong><\/li>\n<li><a href=\"https:\/\/www.apothekesterzing.com\/ratgeber\/mineralstoff-vitaminratgeber\/\" target=\"_blank\" rel=\"noopener\">Gesunde Ern\u00e4hrung mit vielen Vitaminen<\/a> tr\u00e4gt zu Ihrer allgemeinen Gesundheit bei. F\u00fcr Ihre Augen ist Vitamin A besonders zutr\u00e4glich, denn es st\u00e4rkt die Sehkraft und sorgt auf nat\u00fcrliche Weise f\u00fcr Adleraugen.<\/li>\n<li>Besorgen Sie sich ein <strong>Fl\u00e4schchen befeuchtende Augentropfen<\/strong>, idealerweise <strong>hom\u00f6opathische<\/strong>, die den Augen nicht schaden und keinen Gew\u00f6hnungseffekt zur Folge haben. Wenden Sie die Tropfen nach Bedarf an. Beachten Sie aber bitte immer die Gebrauchshinweise sowie das Verfallsdatum. Ist dieses \u00fcberschritten, ersetzen Sie die Tropfen.<\/li>\n<li>F\u00fcr Erfrischung zwischendurch k\u00f6nnen auch <strong>k\u00fchle Teebeutel<\/strong> (vor allem <strong>Schwarztee<\/strong> und <strong>Gr\u00fcntee<\/strong> sind hier empfehlenswert) oder <strong>Gurkenscheiben<\/strong> sorgen, die Sie sich f\u00fcr mindestens zehn Minuten auf die geschlossenen Augenlider legen.<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">#3: F\u00fchren Sie gelegentliche Augenentspannungs\u00fcbungen durch<\/h2>\n<p style=\"text-align: justify;\">Auch mit ein paar einfachen \u00dcbungen k\u00f6nnen Sie Ihre Augen gezielt entspannen. Die besten \u00dcbungen daf\u00fcr werden wir Ihnen nun erkl\u00e4ren:<\/p>\n<p style=\"text-align: justify;\"><strong>Abklopfen und Massieren:<\/strong> Diese \u00dcbung f\u00f6rdert die Durchblutung der Augen und regt die Akupressur an. Legen Sie daf\u00fcr <strong>Zeige- und Mittelfinger zusammen<\/strong>. An den <strong>Innenpunkten der Augenbrauen<\/strong> oberhalb der Nase ansetzen und einmal <strong>um die Augen herumstreichen oder klopfen<\/strong> bis zum unteren Knochenrand unter den Augen. Dabei den Druck langsam steigern. F\u00fchren Sie diese \u00dcbung f\u00fcr 30 bis 60 Sekunden mehrmals t\u00e4glich nach Bedarf durch.<\/p>\n<p style=\"text-align: justify;\"><strong>Blick in die Ferne:<\/strong> Der <strong>Fernblick<\/strong> ist ein hervorragender <strong>Kontrast zur B\u00fcroarbeit<\/strong>, denn dabei wird die <strong>Flexibilit\u00e4t der Augenlinse gef\u00f6rdert<\/strong> \u2013 eine \u00dcbung, die auch Augen\u00e4rzte und Optiker empfehlen. L\u00f6sen Sie den Blick vom Bildschirm und fokussieren Sie nacheinander 5 Objekte in unterschiedlichen Entfernungen \u2013 das k\u00f6nnen Menschen sein, Autos, Geb\u00e4ude, B\u00e4ume oder Stra\u00dfenschilder. Betrachten Sie jedes Objekt ein paar Sekunden lang. F\u00fchren Sie diese \u00dcbung m\u00f6glichst alle 15 Minuten durch.<\/p>\n<p style=\"text-align: justify;\"><strong>An- und Entspannung:<\/strong> Mit dieser \u00dcbung k\u00f6nnen Sie nerv\u00f6ses Augenzucken l\u00f6sen. Halten Sie den Kopf gerade und lassen Sie die Arme locker h\u00e4ngen. <strong>Kneifen Sie die Augen zusammen und rei\u00dfen Sie sie danach \u00fcbertrieben auf<\/strong>. Wiederholen Sie die \u00dcbung acht Mal.<\/p>\n<p style=\"text-align: justify;\"><strong>Aufgepasst bei grauem Star<\/strong>: F\u00fchren Sie hier die \u00dcbung nur leicht aus, kneifen Sie die Augen nicht zusammen!<\/p>\n<p style=\"text-align: justify;\"><strong>Augenkreisen:<\/strong> Bei dieser \u00dcbung trainieren Sie nicht nur die Augenmuskeln, sondern auch beide Gehirnh\u00e4lften. <strong>Schwingen Sie mit dem ausgestreckten Arm nach rechts und links und bauen Sie ganze Kreise ein. Die Augen folgen den Bewegungen<\/strong>. \u00dcbung 2 bis 3 Minuten durchf\u00fchren und so oft wie m\u00f6glich in den Alltag integrieren.<\/p>\n<p style=\"text-align: justify;\"><strong>Blinzeln:<\/strong> Blinzeln l\u00f6st den starren Blick und kurbelt die Produktion des sch\u00fctzenden Tr\u00e4nenfilms an. <strong>Blinzeln Sie eine Minute lang so schnell wie m\u00f6glich<\/strong>, ohne zu verkrampfen. Schlie\u00dfen Sie danach die Augen und genie\u00dfen Sie den wohltuenden Effekt. \u00dcbung nach Bedarf wiederholen.<\/p>\n<p style=\"text-align: justify;\">Palmieren: Die v\u00f6llige Verdunkelung der Augen bewirkt eine v\u00f6llige Entspannung. Hierf\u00fcr <strong>bedecken Sie einfach die geschlossenen Augen mit Ihren H\u00e4nden und lassen die W\u00e4rme und Dunkelheit auf sich wirken.<\/strong> Entfernen Sie nach 2 bis 3 Minuten die H\u00e4nde langsam wieder, um die Augen nicht unn\u00f6tig zu blenden. Wenden Sie die \u00dcbung in den Bildschirmpausen an.<\/p>\n<p style=\"text-align: justify;\"><strong>Lichtbaden:<\/strong> Tanken Sie in der Mittagspause neue Energie, indem Sie Ihr <strong>Gesicht im Freien oder bei ge\u00f6ffnetem Fenster wie in Zeitlupe in der Sonne wenden. Die Augen bleiben dabei geschlossen<\/strong>. Anschlie\u00dfend ausgiebig palmieren.<\/p>\n<p style=\"text-align: justify;\"><strong>Ihre Augen ben\u00f6tigen Deutlich mehr Entspannung, als wir ihnen im Alltag meist erm\u00f6glichen. Gerade, wenn Sie viel am Bildschirm arbeiten, sollten Sie nicht auf gelegentliche Entspannungs\u00fcbungen verzichten, damit Ihre t\u00e4gliche Arbeit nicht zu Kopfschmerzen, M\u00fcdigkeit und Sehkraftverlusten f\u00fchrt. <\/strong><\/p>\n<h3>\u00dcber den Autor:<\/h3>\n<p style=\"text-align: justify;\">Die <a href=\"https:\/\/www.iclinic.at\/\" target=\"_blank\" rel=\"noopener\">iClinic<\/a> in Bratislava z\u00e4hlt zu Europas herausragendsten Kliniken f\u00fcr Augenbehandlungen. Das Spezialgebiet der deutschsprachigen Augenklinik ist die Korrektur von Kurzsichtigkeit, Weitsichtigkeit und Stabsichtigkeit sowie die Behandlung von Augenerkrankungen.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fnuetzliche-tipps-um-muede-augen-im-buero-zu-entspannen%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fnuetzliche-tipps-um-muede-augen-im-buero-zu-entspannen%2F&text=N%C3%BCtzliche%20Tipps%2C%20um%20m%C3%BCde%20Augen%20im%20B%C3%BCro%20zu%20entspannen\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fnuetzliche-tipps-um-muede-augen-im-buero-zu-entspannen%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#126567; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fnuetzliche-tipps-um-muede-augen-im-buero-zu-entspannen%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fnuetzliche-tipps-um-muede-augen-im-buero-zu-entspannen%2F%20N%C3%BCtzliche%20Tipps%2C%20um%20m%C3%BCde%20Augen%20im%20B%C3%BCro%20zu%20entspannen\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fnuetzliche-tipps-um-muede-augen-im-buero-zu-entspannen%2F&media=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fmagazin%2Fwp-content%2Fuploads%2F2024%2F11%2Fcolored-pencils-2024-09-23-04-02-30-utc-scaled.jpg&description=N%C3%BCtzliche%20Tipps%2C%20um%20m%C3%BCde%20Augen%20im%20B%C3%BCro%20zu%20entspannen\" title=\"Bei Pinterest pinnen\" aria-label=\"Bei Pinterest pinnen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#cb2027; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Wer viel am Bildschirm arbeitet, kennt die Probleme, die damit einhergehen: Kopfschmerzen, brennende und trockene Augen, Schlafst\u00f6rungen durch das Blaulicht und sogar nachlassende Sehkraft sind nur einige Auswirkungen, die st\u00e4ndige Arbeit am PC und am Handy mit sich ziehen. Umso wichtiger ist es, den Augen mit ein paar Entspannungs\u00fcbungen f\u00fcr zwischendurch Erholung zu g\u00f6nnen. Beherzigen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9749,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12,1,191],"tags":[136,164,10],"class_list":["post-4753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-training","category-weiterbildung","category-work-life-balance","tag-kurse","tag-stressmanagement","tag-weiterbildungen"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/posts\/4753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/comments?post=4753"}],"version-history":[{"count":4,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/posts\/4753\/revisions"}],"predecessor-version":[{"id":5485,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/posts\/4753\/revisions\/5485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/media\/9749"}],"wp:attachment":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/media?parent=4753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/categories?post=4753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/magazin\/wp-json\/wp\/v2\/tags?post=4753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}