{"id":6192,"date":"2018-01-15T08:50:36","date_gmt":"2018-01-15T07:50:36","guid":{"rendered":"https:\/\/www.weiterbildungsmarkt.net\/news\/?p=6192"},"modified":"2026-01-08T10:44:55","modified_gmt":"2026-01-08T09:44:55","slug":"ams-berufsinfozentren-mit-ibobb-qualitaetssiegel-ausgezeichnet","status":"publish","type":"post","link":"https:\/\/www.weiterbildungsmarkt.net\/news\/ams-berufsinfozentren-mit-ibobb-qualitaetssiegel-ausgezeichnet-6192\/","title":{"rendered":"AMS-Berufsinfozentren mit IBOBB-Qualit\u00e4tssiegel ausgezeichnet"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>&#8222;IBOBB-Zertifikat&#8220; bewertet Qualit\u00e4t der Dienstleistungen<\/strong><\/p>\n<p style=\"text-align: justify;\">Um die Dienstleistungen der Berufsinfozentren (BIZ) auf hohem Niveau zu halten und weiter zu entwickeln, hat das Arbeitsmarktservice (AMS) das \u00d6sterreichische Institut f\u00fcr Berufsbildungsforschung (\u00f6ibf) beauftragt, die Qualit\u00e4t und den Umfang der Beratung, die Ausbildung und Kompetenz der Beraterinnen und Berater sowie viele weitere Aspekte im Rahmen des Qualit\u00e4tssicherungsverfahrens zum &#8222;IBOBB-Zertifikat&#8220; zu bewerten. Expertinnen und Experten aus \u00d6sterreich und Deutschland f\u00fchlten dabei den Berufsinfozentren drei Tage lang \u201eauf den Zahn\u201c. Dabei wurden 14 Qualit\u00e4tskriterien entlang der Qualit\u00e4tsbereiche &#8222;Unabh\u00e4ngigkeit und Kundenorientierung&#8220;, &#8222;strukturelle Voraussetzungen&#8220;, &#8222;Gleichstellungsorientierung&#8220; sowie &#8222;Qualit\u00e4tsentwicklung&#8220; \u00fcberpr\u00fcft und die hohe Qualit\u00e4t der Dienstleistungen der 70 Berufsinfozentren des AMS best\u00e4tigt.<\/p>\n<p style=\"text-align: justify;\">Damit wurden die Berufsinfozentren bereits zum zweiten Mal mit dem Qualit\u00e4tssiegel &#8222;IBOBB-Zertifikat&#8220; f\u00fcr unabh\u00e4ngige Beratung und Information ausgezeichnet. Das IBOBB-Qualit\u00e4tssiegel ist ab sofort f\u00fcr weitere drei Jahre g\u00fcltig und best\u00e4tigt das sehr hohe Niveau der Beratungsleistungen und des professionellen Beratungspersonals. &#8222;Dieses Ergebnis ist eine Auszeichnung f\u00fcr die hervorragende Arbeit, die unsere 250 Beraterinnen und Berater leisten. Es zeigt, dass wir am richtigen Weg sind und unsere Berufsinfozentren den hohen Anforderungen moderner, kundenzentrierter Berufs- und Bildungsberatung entsprechen&#8220;, betonte Sabine Putz, Leiterin der Berufsinformation des AMS \u00d6sterreich.<\/p>\n<p style=\"text-align: justify;\">70 AMS-Berufsinfozentren in ganz \u00d6sterreich Das AMS bietet \u00f6sterreichweit 70 Berufsinfozentren (BIZ) als zentrale Anlaufstellen zur Information und Beratung \u00fcber Berufsinformation sowie \u00fcber Aus- und Weiterbildung. Das Angebot richtet sich an Jugendliche, Schulklassen, Studierende und Erwachsene \u2013 unabh\u00e4ngig davon, ob sie noch in Ausbildung, bereits erwerbst\u00e4tig oder auf Jobsuche sind. Im Vorjahr verzeichneten die Berufsinfozentren insgesamt \u00fcber eine halbe Million Kundinnen und Kunden, darunter knapp 320.000 Einzelbesucher und rund 100.000 Besucher in einer Gruppe (z.B. Schulklasse). Rund 30% der Einzelbesucher waren Jugendliche, bei den Gruppenbesuchern betrug der Anteil Jugendlicher \u00fcber 90%.<\/p>\n<p style=\"text-align: justify;\">Quelle: APA Ots<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fams-berufsinfozentren-mit-ibobb-qualitaetssiegel-ausgezeichnet-6192%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link external external_icon\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fams-berufsinfozentren-mit-ibobb-qualitaetssiegel-ausgezeichnet-6192%2F&text=AMS-Berufsinfozentren%20mit%20IBOBB-Qualit%C3%A4tssiegel%20ausgezeichnet\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fams-berufsinfozentren-mit-ibobb-qualitaetssiegel-ausgezeichnet-6192%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link external external_icon\" style=\"; background-color:#126567; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fams-berufsinfozentren-mit-ibobb-qualitaetssiegel-ausgezeichnet-6192%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link external external_icon\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fams-berufsinfozentren-mit-ibobb-qualitaetssiegel-ausgezeichnet-6192%2F%20AMS-Berufsinfozentren%20mit%20IBOBB-Qualit%C3%A4tssiegel%20ausgezeichnet\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link external external_icon\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fams-berufsinfozentren-mit-ibobb-qualitaetssiegel-ausgezeichnet-6192%2F&media=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fwp-content%2Fuploads%2F2017%2F11%2FNT174.png&description=AMS-Berufsinfozentren%20mit%20IBOBB-Qualit%C3%A4tssiegel%20ausgezeichnet\" title=\"Bei Pinterest pinnen\" aria-label=\"Bei Pinterest pinnen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#cb2027; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>&#8222;IBOBB-Zertifikat&#8220; bewertet Qualit\u00e4t der Dienstleistungen Um die Dienstleistungen der Berufsinfozentren (BIZ) auf hohem Niveau zu halten und weiter zu entwickeln, hat das Arbeitsmarktservice (AMS) das \u00d6sterreichische Institut f\u00fcr Berufsbildungsforschung (\u00f6ibf) beauftragt, die Qualit\u00e4t und den Umfang der Beratung, die Ausbildung und Kompetenz der Beraterinnen und Berater sowie viele weitere Aspekte im Rahmen des Qualit\u00e4tssicherungsverfahrens zum [&hellip;]<\/p>\n","protected":false},"author":192,"featured_media":6108,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[112],"tags":[],"class_list":["post-6192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neuigkeiten"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/posts\/6192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/users\/192"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/comments?post=6192"}],"version-history":[{"count":2,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/posts\/6192\/revisions"}],"predecessor-version":[{"id":9870,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/posts\/6192\/revisions\/9870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/media\/6108"}],"wp:attachment":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/media?parent=6192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/categories?post=6192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/tags?post=6192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}