{"id":9221,"date":"2024-01-23T10:39:18","date_gmt":"2024-01-23T09:39:18","guid":{"rendered":"https:\/\/www.weiterbildungsmarkt.net\/news\/?p=9221"},"modified":"2026-01-02T10:18:26","modified_gmt":"2026-01-02T09:18:26","slug":"studie-klares-ja-zu-kuenstlicher-intelligenz-am-arbeitsplatz","status":"publish","type":"post","link":"https:\/\/www.weiterbildungsmarkt.net\/news\/studie-klares-ja-zu-kuenstlicher-intelligenz-am-arbeitsplatz-9221\/","title":{"rendered":"Studie: Klares &#8222;Ja&#8220; zu K\u00fcnstlicher Intelligenz am Arbeitsplatz"},"content":{"rendered":"<p style=\"text-align: justify;\">Arbeitnehmende in Deutschland sind dem technischen Fortschritt am eigenen Arbeitsplatz gegen\u00fcber \u00e4u\u00dferst offen und positiv eingestellt &#8211; dies ist eine der wichtigsten Erkenntnisse der repr\u00e4sentativen Studie der Adecco Group zur Arbeitswelt der Zukunft (Report &#8222;Global Workforce of the Future&#8220;).<\/p>\n<p style=\"text-align: justify;\">An der Studie haben weltweit rund 30.000 Arbeitnehmende aus 23 L\u00e4ndern teilgenommen, davon rund 2.000 in Deutschland. Der thematische Schwerpunkt der Studie lag auf den zu erwartenden Auswirkungen von generativer K\u00fcnstlicher Intelligenz (KI) am Arbeitsplatz sowie dem pers\u00f6nlichen Umgang damit.<\/p>\n<p style=\"text-align: justify;\">Die Ergebnisse aus Deutschland stechen hervor: So gab beispielsweise in Finnland (51 Prozent) nur etwa jeder zweite Arbeitnehmende an, am Arbeitsplatz mit K\u00fcnstlicher Intelligenz zu arbeiten. Und auch in Japan (54 Prozent), im deutschen Nachbarland Frankreich (66 Prozent) sowie im weltweiten Durchschnitt (70 Prozent) sind die Werte geringer als in Deutschland. Hierzulande nutzen nach eigenen Angaben 74 Prozent der Befragten bereits generative KI im Arbeitsalltag.<\/p>\n<p style=\"text-align: justify;\"><strong>Weiterentwicklung von F\u00e4higkeiten von gr\u00f6\u00dfter Bedeutung<\/strong><\/p>\n<p style=\"text-align: justify;\">Peter Blersch, Deutschlandchef der Adecco Group: &#8222;Diese Ergebnisse sind f\u00fcr deutsche Unternehmen durchaus Grund zu Hoffnung. Die Welt der Arbeit wird sich durch generative KI stark transformieren. Prognosen zufolge ver\u00e4ndern sich in den kommenden Jahren weltweit mehr als 300 Millionen Berufsprofile. Es ist darum positiv, dass deutsche Arbeitnehmende den neuen Technologien so offen gegen\u00fcberstehen. Speziell der qualifizierten Weiterbildung von Arbeitnehmenden wird f\u00fcr Unternehmen jetzt eine besondere Bedeutung zukommen, um KI auch sicher und produktiv einsetzen zu k\u00f6nnen. Als Personaldienstleister arbeiten wir aktiv daran mit, dass Arbeitnehmende kontinuierlich dazu bef\u00e4higt werden. Die Weiterentwicklung von F\u00e4higkeiten wird zu einer der wichtigsten Investitionen auf dem deutschen Arbeitsmarkt.&#8220;<\/p>\n<p style=\"text-align: justify;\">Die Adecco Group selbst hat vor Kurzem eine Absichtserkl\u00e4rung mit dem Technologieunternehmen Microsoft unterzeichnet. Die auf ihren jeweiligen Gebieten f\u00fchrenden Unternehmen wollen Arbeitnehmende gemeinsam auf die Zukunft vorbereiten und ihre Besch\u00e4ftigungsf\u00e4higkeit sichern. Im Zentrum steht unter anderem die Entwicklung einer Karriereplattform, die selbst auf KI basiert und ma\u00dfgeschneiderte Karriereberatung und Dienstleistungen in den Bereichen Coaching, Mikro-Learning und Weiterqualifizierung anbieten wird, um nachhaltige Besch\u00e4ftigungsf\u00e4higkeit zu sichern.<\/p>\n<p style=\"text-align: justify;\"><strong>Mentale Gesundheit gewinnt an Bedeutung<\/strong><\/p>\n<p style=\"text-align: justify;\">Gerade in Zeiten starker Transformation r\u00fcckt auch das Thema mentale Gesundheit in den Vordergrund: 54 Prozent der Arbeitnehmenden in Deutschland gaben im Rahmen der Studie an, in den vergangenen zw\u00f6lf Monaten beruflich bedingt Anzeichen von Burnout versp\u00fcrt zu haben. Im globalen Vergleich zwar ein geringerer Wert (Japan: 56 Prozent, Frankreich: 60 Prozent, weltweiter Durchschnitt: 65 Prozent), dennoch aber keine erfreuliche Nachricht. &#8222;Auch bei der Besch\u00e4ftigung mit K\u00fcnstlicher Intelligenz muss der Mensch im Fokus stehen&#8220;, appelliert Peter Blersch. &#8222;Unternehmen haben die Verantwortung, auf die mentale Gesundheit ihrer Arbeitnehmenden Acht zu geben.&#8220;<\/p>\n<p style=\"text-align: justify;\"><strong>Wechselbereitschaft sinkt<\/strong><\/p>\n<p style=\"text-align: justify;\">Weitere Ergebnisse der Studie geben unter anderem Auskunft zur Bereitschaft der Arbeitnehmenden, in den kommenden zw\u00f6lf Monaten ihren Arbeitgeber wechseln zu wollen. In Deutschland ist diese Bereitschaft der Studie zufolge von 25 Prozent (2022) auf 21 Prozent (2023) gesunken. In Frankreich (28 und 24 Prozent), Japan (jeweils 23 Prozent) sowie ebenso im weltweiten Durchschnitt (27 und 22 Prozent) fallen die Werte hingegen h\u00f6her aus.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00dcber die Studie:<\/strong><\/p>\n<p style=\"text-align: justify;\">Der Report &#8222;Global Workforce Of The Future&#8220; wird 2023 bereits zum vierten Mal ver\u00f6ffentlicht. Befragt wurden weltweit rund 30.000 Arbeitnehmende in 23 L\u00e4ndern aus verschiedenen Branchen wie Gesundheitswesen oder Einzelhandel sowie unterschiedlichen Alters und Geschlecht, vom Berufseinsteiger bis zur F\u00fchrungskraft. In Deutschland nahmen rund 2000 Arbeitnehmende an der Befragung teil. Erhoben wurden die Ergebnisse im Zeitraum Juli bis August 2023. &#8222;Global Workforce Of The Future&#8220; gibt Antworten auf Fragen rund um die derzeitigen und k\u00fcnftigen Bedingungen am Arbeitsplatz, unter anderem zu k\u00fcnstlicher Intelligenz, Wechselbereitschaft, der Gehaltszufriedenheit oder der mentalen Gesundheit von Arbeitnehmenden.<\/p>\n<p style=\"text-align: justify;\">Der 52-seitige Report &#8222;Global Workforce Of The Future&#8220; ist unter folgendem Link abrufbar: https:\/\/www.adeccogroup.de\/global-workforce-of-the-future\/<\/p>\n<p style=\"text-align: justify;\"><strong>\u00dcber die Adecco Group:<\/strong><\/p>\n<p style=\"text-align: justify;\">Die Adecco Group geh\u00f6rt zu den weltweit f\u00fchrenden Dienstleistungsunternehmen im Bereich Human Resources. \u00dcber ihre spezialisierten Gesch\u00e4ftseinheiten qualifiziert, entwickelt und vermittelt sie Mitarbeitende in 60 L\u00e4nder weltweit und ber\u00e4t Unternehmen zu individuellen Personall\u00f6sungen. Mit dem Ziel, eine gute Zukunft f\u00fcr alle zu gestalten, verpflichtet sich die Adecco Group zu verantwortungsvollem Handeln und arbeitet jeden Tag daran, eine bessere Arbeitswelt f\u00fcr alle zu schaffen.<\/p>\n<p style=\"text-align: justify;\">Quelle: Presseportal.de<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fstudie-klares-ja-zu-kuenstlicher-intelligenz-am-arbeitsplatz-9221%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link external external_icon\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fstudie-klares-ja-zu-kuenstlicher-intelligenz-am-arbeitsplatz-9221%2F&text=Studie%3A%20Klares%20%E2%80%9EJa%E2%80%9C%20zu%20K%C3%BCnstlicher%20Intelligenz%20am%20Arbeitsplatz\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fstudie-klares-ja-zu-kuenstlicher-intelligenz-am-arbeitsplatz-9221%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link external external_icon\" style=\"; background-color:#126567; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fstudie-klares-ja-zu-kuenstlicher-intelligenz-am-arbeitsplatz-9221%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link external external_icon\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fstudie-klares-ja-zu-kuenstlicher-intelligenz-am-arbeitsplatz-9221%2F%20Studie%3A%20Klares%20%E2%80%9EJa%E2%80%9C%20zu%20K%C3%BCnstlicher%20Intelligenz%20am%20Arbeitsplatz\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link external external_icon\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fstudie-klares-ja-zu-kuenstlicher-intelligenz-am-arbeitsplatz-9221%2F&media=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fwp-content%2Fuploads%2F2016%2F09%2FTrendStudien3.png&description=Studie%3A%20Klares%20%E2%80%9EJa%E2%80%9C%20zu%20K%C3%BCnstlicher%20Intelligenz%20am%20Arbeitsplatz\" title=\"Bei Pinterest pinnen\" aria-label=\"Bei Pinterest pinnen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#cb2027; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Arbeitnehmende in Deutschland sind dem technischen Fortschritt am eigenen Arbeitsplatz gegen\u00fcber \u00e4u\u00dferst offen und positiv eingestellt &#8211; dies ist eine der wichtigsten Erkenntnisse der repr\u00e4sentativen Studie der Adecco Group zur Arbeitswelt der Zukunft (Report &#8222;Global Workforce of the Future&#8220;). An der Studie haben weltweit rund 30.000 Arbeitnehmende aus 23 L\u00e4ndern teilgenommen, davon rund 2.000 in [&hellip;]<\/p>\n","protected":false},"author":193,"featured_media":3636,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[110,112,1],"tags":[],"class_list":["post-9221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-studien","category-neuigkeiten","category-weiterbildung"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/posts\/9221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/users\/193"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/comments?post=9221"}],"version-history":[{"count":3,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/posts\/9221\/revisions"}],"predecessor-version":[{"id":9617,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/posts\/9221\/revisions\/9617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/media\/3636"}],"wp:attachment":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/media?parent=9221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/categories?post=9221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/tags?post=9221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}