{"id":9318,"date":"2024-05-28T09:24:59","date_gmt":"2024-05-28T07:24:59","guid":{"rendered":"https:\/\/www.weiterbildungsmarkt.net\/news\/?p=9318"},"modified":"2024-05-27T14:26:24","modified_gmt":"2024-05-27T12:26:24","slug":"ki-in-unternehmen-bereits-unverzichtbar-oder-noch-ungenutzt","status":"publish","type":"post","link":"https:\/\/www.weiterbildungsmarkt.net\/news\/ki-in-unternehmen-bereits-unverzichtbar-oder-noch-ungenutzt-9318\/","title":{"rendered":"KI in Unternehmen: Bereits unverzichtbar oder noch ungenutzt?"},"content":{"rendered":"<p style=\"text-align: justify;\">Viele F\u00fchrungskr\u00e4fte haben eine ambivalente Haltung gegen\u00fcber einem verst\u00e4rkten KI-Einsatz und forcieren diesen deshalb in ihrem Bereich eher z\u00f6gerlich. Das ergab eine Online-Befragung von F\u00fchrungskr\u00e4ften des IFIDZ.<\/p>\n<p style=\"text-align: justify;\">Wie stark werden KI-Tools in den Unternehmen sowie von deren F\u00fchrungskr\u00e4ften in ihrem Arbeitsalltag schon genutzt und inwieweit erwarten sie, dass sich durch deren Einsatz die F\u00fchrungskultur in den Betrieben ver\u00e4ndert?<\/p>\n<p style=\"text-align: justify;\">Das wollte das Institut f\u00fcr F\u00fchrungskultur im digitalen Zeitalter (IFIDZ), Wiesbaden, bei seinem j\u00fcngsten Leadership-Trendbarometer von den teilnehmenden F\u00fchrungskr\u00e4ften wissen. Die Online-Befragung von 173 F\u00fchrungskr\u00e4ften in Unternehmen aus verschiedenen Branchen ergab, dass die meisten von ihnen ein ambivalentes Verh\u00e4ltnis zur KI-Nutzung in ihrem Betrieb sowie in ihrem eigenen Arbeitsalltag haben.<\/p>\n<p style=\"text-align: justify;\"><strong>F\u00fchrungskr\u00e4fte erachten den KI-Einsatz als erfolgsrelevant\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">So sind zwar 80 Prozent der befragten F\u00fchrungskr\u00e4fte davon \u00fcberzeugt, dass ein professioneller KI-Einsatz in ihrer Branche k\u00fcnftig eine erfolgsentscheidende Rolle spielen wird; nur 22 Prozent von ihnen nutzen solche KI-Tools wie ChatGPT, Deepl und Copilot jedoch heute bereits nahezu t\u00e4glich.<\/p>\n<p style=\"text-align: justify;\">Zudem setzen sich nur 21 Prozent von ihnen aktiv f\u00fcr eine st\u00e4rkere Nutzung der KI-Technik in ihrem Arbeitsumfeld ein. Dies d\u00fcrfte auch daran liegen, dass mehr als ein Drittel (35 Prozent) von ihnen angeben, in ihrem Betrieb diesbez\u00fcglich keinerlei Unterst\u00fctzung zu erfahren.<\/p>\n<p style=\"text-align: justify;\"><strong>\u2026 forcieren die KI-Nutzung aber eher z\u00f6gerlich. <\/strong><\/p>\n<p style=\"text-align: justify;\">Damit korrespondiert, dass nur 26,3 Prozent der F\u00fchrungskr\u00e4fte sich zentral daf\u00fcr verantwortlich f\u00fchlen, den KI-Einsatz in ihrem Verantwortungsbereich zu stimulieren. Die meisten von ihnen f\u00fchlen sich nur bedingt hierf\u00fcr zust\u00e4ndig. Dies deutet nach Auffassung des IFIDZ auf ein \u201esignifikantes Engagement-Defizit\u201c der F\u00fchrungskr\u00e4fte im KI-Bereich hin.<\/p>\n<p style=\"text-align: justify;\">Dem widerspricht, dass<\/p>\n<ul style=\"text-align: justify;\"><br \/>\n<li>46 Prozent der F\u00fchrungskr\u00e4fte angeben, ihre Unternehmen b\u00f6ten f\u00fcr ihre Mitarbeiter bereits Schulungen an, um die KI-Integration zu unterst\u00fctzen, und<\/li><br \/>\n<li>\u00fcber 40 Prozent \u00e4u\u00dfern, das Thema KI spiele bei ihren strategischen Planungen bereits eine wichtige Rolle.<\/li><br \/>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Dem mittleren Management fehlt oft die n\u00f6tige Orientierung <\/strong><\/p>\n<p style=\"text-align: justify;\">Die oft inkonsistenten Aussagen der F\u00fchrungskr\u00e4fte bei der Befragung zeigen nach Auffassung der Gr\u00fcnderin und Leiterin des IFIDZ Barbara Liebermeister, dass sich viele von ihnen dem Thema KI-Einsatz in ihrem Bereich und Arbeitsalltag \u201eaktuell noch wenig systematisch und eher z\u00f6gerlich n\u00e4hern\u201c \u2013 auch weil in ihren Unternehmen noch kein Konsens bzw. Alignment dar\u00fcber existiert, wie mit diesem Zukunftsthema umzugehen ist. Auch entsprechende strategische Vorgaben fehlen.<\/p>\n<p style=\"text-align: justify;\">Als Gr\u00fcnde f\u00fcr ihr eher geringes Engagement f\u00fcr einen st\u00e4rkeren KI-Einsatz nennen die F\u00fchrungskr\u00e4fte unter anderem Datenschutzbedenken, die in ihrer Organisation diesbez\u00fcglich bestehen. Au\u00dferdem sehen bei einem verst\u00e4rkten KI-Einsatz mittelfristig durchaus die Gefahr, dass damit ein Verlust von Arbeitspl\u00e4tzen einhergeht \u2013 insbesondere dann, wenn dieser zu einer verst\u00e4rkten Automatisierung gewisser Aufgaben und Prozesse f\u00fchrt.<\/p>\n<p style=\"text-align: justify;\"><strong>Nicht wenige F\u00fchrungskr\u00e4fte f\u00fchlen sich von der KI latent bedroht<\/strong><\/p>\n<p style=\"text-align: justify;\">Etwa 20 Prozent f\u00fchlen sich hiervon sogar selbst mehr oder minder stark bedroht, unter anderem, weil bei einer eventuell sinkenden Mitarbeiterzahl auch weniger F\u00fchrungskr\u00e4fte ben\u00f6tigt werden.<\/p>\n<p style=\"text-align: justify;\">Die Ergebnisse des aktuellen Leadership-Trendbarometers des IFIDZ flie\u00dfen k\u00fcnftig auch in die (Online-)Seminare und Vortr\u00e4ge ein, die Barbara Liebermeister regelm\u00e4\u00dfig in und f\u00fcr Unternehmen zum Thema \u201eF\u00fchrung im Kontext k\u00fcnstlicher Intelligenz (KI)\u201c h\u00e4lt. N\u00e4here Infos hier\u00fcber finden Interessierte in der Rubrik \u201eLeistungen\u201c auf der IFIDZ-Webseite.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fki-in-unternehmen-bereits-unverzichtbar-oder-noch-ungenutzt-9318%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link external external_icon\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fki-in-unternehmen-bereits-unverzichtbar-oder-noch-ungenutzt-9318%2F&text=KI%20in%20Unternehmen%3A%20Bereits%20unverzichtbar%20oder%20noch%20ungenutzt%3F\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fki-in-unternehmen-bereits-unverzichtbar-oder-noch-ungenutzt-9318%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link external external_icon\" style=\"; background-color:#126567; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fki-in-unternehmen-bereits-unverzichtbar-oder-noch-ungenutzt-9318%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link external external_icon\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fki-in-unternehmen-bereits-unverzichtbar-oder-noch-ungenutzt-9318%2F%20KI%20in%20Unternehmen%3A%20Bereits%20unverzichtbar%20oder%20noch%20ungenutzt%3F\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link external external_icon\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fki-in-unternehmen-bereits-unverzichtbar-oder-noch-ungenutzt-9318%2F&media=https%3A%2F%2Fwww.weiterbildungsmarkt.net%2Fnews%2Fwp-content%2Fuploads%2F2017%2F11%2FNT174.png&description=KI%20in%20Unternehmen%3A%20Bereits%20unverzichtbar%20oder%20noch%20ungenutzt%3F\" title=\"Bei Pinterest pinnen\" aria-label=\"Bei Pinterest pinnen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#cb2027; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Viele F\u00fchrungskr\u00e4fte haben eine ambivalente Haltung gegen\u00fcber einem verst\u00e4rkten KI-Einsatz und forcieren diesen deshalb in ihrem Bereich eher z\u00f6gerlich. Das ergab eine Online-Befragung von F\u00fchrungskr\u00e4ften des IFIDZ. Wie stark werden KI-Tools in den Unternehmen sowie von deren F\u00fchrungskr\u00e4ften in ihrem Arbeitsalltag schon genutzt und inwieweit erwarten sie, dass sich durch deren Einsatz die F\u00fchrungskultur in [&hellip;]<\/p>\n","protected":false},"author":192,"featured_media":6108,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[110,112],"tags":[],"class_list":["post-9318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-studien","category-neuigkeiten"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/posts\/9318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/users\/192"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/comments?post=9318"}],"version-history":[{"count":2,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/posts\/9318\/revisions"}],"predecessor-version":[{"id":9320,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/posts\/9318\/revisions\/9320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/media\/6108"}],"wp:attachment":[{"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/media?parent=9318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/categories?post=9318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weiterbildungsmarkt.net\/news\/wp-json\/wp\/v2\/tags?post=9318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}